{"id":58087,"date":"2022-11-23T09:19:51","date_gmt":"2022-11-23T08:19:51","guid":{"rendered":"https:\/\/www.blackfridaydeals.ch\/lego-42115-lamborghini-mit-manor-karte\/"},"modified":"2022-12-02T14:34:11","modified_gmt":"2022-12-02T13:34:11","slug":"lego-42115-lamborghini-mit-manor-karte","status":"publish","type":"post","link":"https:\/\/www.blackfridaydeals.ch\/fr\/lego-42115-lamborghini-mit-manor-karte\/","title":{"rendered":"LEGO Lamborghini la carte Manor"},"content":{"rendered":"<p>Chez Manor, vous b\u00e9n\u00e9ficiez d&#8217;un rabais de 30% sur le set LEGO 42115 Lamborghini Si\u00e1n FKP 37 si vous indiquez votre carte Manor lors de votre achat. Vous pouvez ainsi acheter le set Lego pour CHF 279.30.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chez Manor, vous b\u00e9n\u00e9ficiez d&#8217;un rabais de 30% sur le set LEGO 42115 Lamborghini Si\u00e1n FKP 37 si vous indiquez votre carte Manor lors de votre achat. Vous pouvez ainsi acheter le set Lego pour CHF 279.30. &nbsp;<\/p>\n","protected":false},"author":40,"featured_media":58037,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[14212],"tags":[16054],"dealstore":[375],"offerexpiration":[16317],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>LEGO Lamborghini la carte Manor - blackfridaydeals.ch<\/title>\n<meta name=\"description\" content=\"Chez Manor, vous b\u00e9n\u00e9ficiez d&#039;un rabais de 30% sur le set LEGO 42115 Lamborghini Si\u00e1n FKP 37 si vous indiquez votre carte Manor lors de votre achat. Vous\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LEGO Lamborghini la carte Manor - blackfridaydeals.ch\" \/>\n<meta property=\"og:description\" content=\"Chez Manor, vous b\u00e9n\u00e9ficiez d&#039;un rabais de 30% sur le set LEGO 42115 Lamborghini Si\u00e1n FKP 37 si vous indiquez votre carte Manor lors de votre achat. Vous\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.blackfridaydeals.ch\/fr\/lego-42115-lamborghini-mit-manor-karte\/\" \/>\n<meta property=\"og:site_name\" content=\"blackfridaydeals.ch\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/blackfridaydealsch\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/jueluz\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-23T08:19:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-02T13:34:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.blackfridaydeals.ch\/wp-content\/uploads\/2022\/11\/42115.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Julian Zrotz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@blackfridaych\" \/>\n<meta name=\"twitter:site\" content=\"@blackfridaych\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Julian Zrotz\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/lego-42115-lamborghini-mit-manor-karte\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/lego-42115-lamborghini-mit-manor-karte\/\"},\"author\":{\"name\":\"Julian Zrotz\",\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/#\/schema\/person\/9100d4e4886da9d8414fa37987571c62\"},\"headline\":\"LEGO Lamborghini la carte Manor\",\"datePublished\":\"2022-11-23T08:19:51+00:00\",\"dateModified\":\"2022-12-02T13:34:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/lego-42115-lamborghini-mit-manor-karte\/\"},\"wordCount\":42,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/#organization\"},\"keywords\":[\"top-top-deals-fr\"],\"articleSection\":[\"Top-Deals\"],\"inLanguage\":\"fr-CH\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.blackfridaydeals.ch\/fr\/lego-42115-lamborghini-mit-manor-karte\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/lego-42115-lamborghini-mit-manor-karte\/\",\"url\":\"https:\/\/www.blackfridaydeals.ch\/fr\/lego-42115-lamborghini-mit-manor-karte\/\",\"name\":\"LEGO Lamborghini la carte Manor - blackfridaydeals.ch\",\"isPartOf\":{\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/#website\"},\"datePublished\":\"2022-11-23T08:19:51+00:00\",\"dateModified\":\"2022-12-02T13:34:11+00:00\",\"description\":\"Chez Manor, vous b\u00e9n\u00e9ficiez d'un rabais de 30% sur le set LEGO 42115 Lamborghini Si\u00e1n FKP 37 si vous indiquez votre carte Manor lors de votre achat. Vous\",\"breadcrumb\":{\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/lego-42115-lamborghini-mit-manor-karte\/#breadcrumb\"},\"inLanguage\":\"fr-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.blackfridaydeals.ch\/fr\/lego-42115-lamborghini-mit-manor-karte\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/lego-42115-lamborghini-mit-manor-karte\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.blackfridaydeals.ch\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LEGO Lamborghini la carte Manor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/#website\",\"url\":\"https:\/\/www.blackfridaydeals.ch\/fr\/\",\"name\":\"blackfridaydeals.ch\",\"description\":\"Alle Angebote des Black Friday 2025 in der Schweiz\",\"publisher\":{\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/#organization\"},\"alternateName\":\"Black Friday Deals\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.blackfridaydeals.ch\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-CH\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/#organization\",\"name\":\"blackfridaydeals.ch\",\"alternateName\":\"Black Friday Deals\",\"url\":\"https:\/\/www.blackfridaydeals.ch\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CH\",\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.blackfridaydeals.ch\/wp-content\/uploads\/2023\/03\/app-icon-white-bg-jpg.jpg\",\"contentUrl\":\"https:\/\/www.blackfridaydeals.ch\/wp-content\/uploads\/2023\/03\/app-icon-white-bg-jpg.jpg\",\"width\":512,\"height\":512,\"caption\":\"blackfridaydeals.ch\"},\"image\":{\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/blackfridaydealsch\/\",\"https:\/\/twitter.com\/blackfridaych\",\"https:\/\/www.youtube.com\/channel\/UCNKXHacMw8AS34mBgzVx3FQ\",\"https:\/\/www.instagram.com\/blackfridaydeals.ch\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/#\/schema\/person\/9100d4e4886da9d8414fa37987571c62\",\"name\":\"Julian Zrotz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CH\",\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/da49c5ffe2b85d94c98cb0e0c28802e6?s=96&d=blank&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/da49c5ffe2b85d94c98cb0e0c28802e6?s=96&d=blank&r=g\",\"caption\":\"Julian Zrotz\"},\"description\":\"Bereits Jahre bevor der Black Friday in der Schweiz ankam, informierte sich Julian Zrotz \u00fcber das Shopping-Event in verschiedenen englischsprachigen Medien. Im 2015, als Manor als erster grosser Schweizer H\u00e4ndler das Event in die Schweiz brachte, besuchte Zrotz mehrere Filialen des Warenhauskonzerns, um aus erster Hand den Impact zu erleben, den das Shopping-Event in der Schweiz hat. Er beschloss blackfridaydeals.ch zu gr\u00fcnden. Seither informiert Julian Zrotz die Schweiz \u00fcber den Black Friday. Einerseits mit allgemeinen Informationen, Tipps &amp; Tricks und Prognosen zu allen grossen Schweizer Shops auf der Website blackfridaydeals.ch. Andererseits ist er ein gefragter Gespr\u00e4chspartner f\u00fcr Schweizer Medien. Mit seinen zahlreichen Medienauftritten hat er sich als der Black Friday Experte in der Schweiz etabliert.\",\"sameAs\":[\"https:\/\/www.facebook.com\/jueluz\/\",\"https:\/\/ch.linkedin.com\/in\/julian-zrotz-a4158119\"],\"url\":\"https:\/\/www.blackfridaydeals.ch\/fr\/author\/juelu\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LEGO Lamborghini la carte Manor - blackfridaydeals.ch","description":"Chez Manor, vous b\u00e9n\u00e9ficiez d'un rabais de 30% sur le set LEGO 42115 Lamborghini Si\u00e1n FKP 37 si vous indiquez votre carte Manor lors de votre achat. Vous","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"LEGO Lamborghini la carte Manor - blackfridaydeals.ch","og_description":"Chez Manor, vous b\u00e9n\u00e9ficiez d'un rabais de 30% sur le set LEGO 42115 Lamborghini Si\u00e1n FKP 37 si vous indiquez votre carte Manor lors de votre achat. Vous","og_url":"https:\/\/www.blackfridaydeals.ch\/fr\/lego-42115-lamborghini-mit-manor-karte\/","og_site_name":"blackfridaydeals.ch","article_publisher":"https:\/\/www.facebook.com\/blackfridaydealsch\/","article_author":"https:\/\/www.facebook.com\/jueluz\/","article_published_time":"2022-11-23T08:19:51+00:00","article_modified_time":"2022-12-02T13:34:11+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/www.blackfridaydeals.ch\/wp-content\/uploads\/2022\/11\/42115.jpeg","type":"image\/jpeg"}],"author":"Julian Zrotz","twitter_card":"summary_large_image","twitter_creator":"@blackfridaych","twitter_site":"@blackfridaych","twitter_misc":{"Written by":"Julian Zrotz"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.blackfridaydeals.ch\/fr\/lego-42115-lamborghini-mit-manor-karte\/#article","isPartOf":{"@id":"https:\/\/www.blackfridaydeals.ch\/fr\/lego-42115-lamborghini-mit-manor-karte\/"},"author":{"name":"Julian Zrotz","@id":"https:\/\/www.blackfridaydeals.ch\/fr\/#\/schema\/person\/9100d4e4886da9d8414fa37987571c62"},"headline":"LEGO Lamborghini la carte Manor","datePublished":"2022-11-23T08:19:51+00:00","dateModified":"2022-12-02T13:34:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.blackfridaydeals.ch\/fr\/lego-42115-lamborghini-mit-manor-karte\/"},"wordCount":42,"commentCount":0,"publisher":{"@id":"https:\/\/www.blackfridaydeals.ch\/fr\/#organization"},"keywords":["top-top-deals-fr"],"articleSection":["Top-Deals"],"inLanguage":"fr-CH","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.blackfridaydeals.ch\/fr\/lego-42115-lamborghini-mit-manor-karte\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.blackfridaydeals.ch\/fr\/lego-42115-lamborghini-mit-manor-karte\/","url":"https:\/\/www.blackfridaydeals.ch\/fr\/lego-42115-lamborghini-mit-manor-karte\/","name":"LEGO Lamborghini la carte Manor - blackfridaydeals.ch","isPartOf":{"@id":"https:\/\/www.blackfridaydeals.ch\/fr\/#website"},"datePublished":"2022-11-23T08:19:51+00:00","dateModified":"2022-12-02T13:34:11+00:00","description":"Chez Manor, vous b\u00e9n\u00e9ficiez d'un rabais de 30% sur le set LEGO 42115 Lamborghini Si\u00e1n FKP 37 si vous indiquez votre carte Manor lors de votre achat. Vous","breadcrumb":{"@id":"https:\/\/www.blackfridaydeals.ch\/fr\/lego-42115-lamborghini-mit-manor-karte\/#breadcrumb"},"inLanguage":"fr-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.blackfridaydeals.ch\/fr\/lego-42115-lamborghini-mit-manor-karte\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.blackfridaydeals.ch\/fr\/lego-42115-lamborghini-mit-manor-karte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.blackfridaydeals.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"LEGO Lamborghini la carte Manor"}]},{"@type":"WebSite","@id":"https:\/\/www.blackfridaydeals.ch\/fr\/#website","url":"https:\/\/www.blackfridaydeals.ch\/fr\/","name":"blackfridaydeals.ch","description":"Alle Angebote des Black Friday 2025 in der Schweiz","publisher":{"@id":"https:\/\/www.blackfridaydeals.ch\/fr\/#organization"},"alternateName":"Black Friday Deals","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.blackfridaydeals.ch\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-CH"},{"@type":"Organization","@id":"https:\/\/www.blackfridaydeals.ch\/fr\/#organization","name":"blackfridaydeals.ch","alternateName":"Black Friday Deals","url":"https:\/\/www.blackfridaydeals.ch\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-CH","@id":"https:\/\/www.blackfridaydeals.ch\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.blackfridaydeals.ch\/wp-content\/uploads\/2023\/03\/app-icon-white-bg-jpg.jpg","contentUrl":"https:\/\/www.blackfridaydeals.ch\/wp-content\/uploads\/2023\/03\/app-icon-white-bg-jpg.jpg","width":512,"height":512,"caption":"blackfridaydeals.ch"},"image":{"@id":"https:\/\/www.blackfridaydeals.ch\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/blackfridaydealsch\/","https:\/\/twitter.com\/blackfridaych","https:\/\/www.youtube.com\/channel\/UCNKXHacMw8AS34mBgzVx3FQ","https:\/\/www.instagram.com\/blackfridaydeals.ch\/"]},{"@type":"Person","@id":"https:\/\/www.blackfridaydeals.ch\/fr\/#\/schema\/person\/9100d4e4886da9d8414fa37987571c62","name":"Julian Zrotz","image":{"@type":"ImageObject","inLanguage":"fr-CH","@id":"https:\/\/www.blackfridaydeals.ch\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/da49c5ffe2b85d94c98cb0e0c28802e6?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/da49c5ffe2b85d94c98cb0e0c28802e6?s=96&d=blank&r=g","caption":"Julian Zrotz"},"description":"Bereits Jahre bevor der Black Friday in der Schweiz ankam, informierte sich Julian Zrotz \u00fcber das Shopping-Event in verschiedenen englischsprachigen Medien. Im 2015, als Manor als erster grosser Schweizer H\u00e4ndler das Event in die Schweiz brachte, besuchte Zrotz mehrere Filialen des Warenhauskonzerns, um aus erster Hand den Impact zu erleben, den das Shopping-Event in der Schweiz hat. Er beschloss blackfridaydeals.ch zu gr\u00fcnden. Seither informiert Julian Zrotz die Schweiz \u00fcber den Black Friday. Einerseits mit allgemeinen Informationen, Tipps &amp; Tricks und Prognosen zu allen grossen Schweizer Shops auf der Website blackfridaydeals.ch. Andererseits ist er ein gefragter Gespr\u00e4chspartner f\u00fcr Schweizer Medien. Mit seinen zahlreichen Medienauftritten hat er sich als der Black Friday Experte in der Schweiz etabliert.","sameAs":["https:\/\/www.facebook.com\/jueluz\/","https:\/\/ch.linkedin.com\/in\/julian-zrotz-a4158119"],"url":"https:\/\/www.blackfridaydeals.ch\/fr\/author\/juelu\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.blackfridaydeals.ch\/fr\/wp-json\/wp\/v2\/posts\/58087"}],"collection":[{"href":"https:\/\/www.blackfridaydeals.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blackfridaydeals.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blackfridaydeals.ch\/fr\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blackfridaydeals.ch\/fr\/wp-json\/wp\/v2\/comments?post=58087"}],"version-history":[{"count":3,"href":"https:\/\/www.blackfridaydeals.ch\/fr\/wp-json\/wp\/v2\/posts\/58087\/revisions"}],"predecessor-version":[{"id":58095,"href":"https:\/\/www.blackfridaydeals.ch\/fr\/wp-json\/wp\/v2\/posts\/58087\/revisions\/58095"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.blackfridaydeals.ch\/fr\/wp-json\/wp\/v2\/media\/58037"}],"wp:attachment":[{"href":"https:\/\/www.blackfridaydeals.ch\/fr\/wp-json\/wp\/v2\/media?parent=58087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blackfridaydeals.ch\/fr\/wp-json\/wp\/v2\/categories?post=58087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blackfridaydeals.ch\/fr\/wp-json\/wp\/v2\/tags?post=58087"},{"taxonomy":"dealstore","embeddable":true,"href":"https:\/\/www.blackfridaydeals.ch\/fr\/wp-json\/wp\/v2\/dealstore?post=58087"},{"taxonomy":"offerexpiration","embeddable":true,"href":"https:\/\/www.blackfridaydeals.ch\/fr\/wp-json\/wp\/v2\/offerexpiration?post=58087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}