{"id":45450,"date":"2021-11-23T16:21:54","date_gmt":"2021-11-23T15:21:54","guid":{"rendered":"https:\/\/www.blackfridaydeals.ch\/?p=45450"},"modified":"2021-12-14T10:59:31","modified_gmt":"2021-12-14T09:59:31","slug":"rabais-chez-hugo-boss","status":"publish","type":"post","link":"https:\/\/www.blackfridaydeals.ch\/fr\/rabais-chez-hugo-boss\/","title":{"rendered":"Jusqu&#8217;\u00e0 40% chez Hugo Boss"},"content":{"rendered":"<p>Chez Hugo Boss, le Black Friday offre jusqu&#8217;\u00e0 40% de r\u00e9duction sur des cat\u00e9gories qui changent tous les jours. Cela vaut donc la peine d&#8217;y jeter un coup d&#8217;\u0153il tous les jours !<\/p>\n<p>Que ce soit un costume \u00e9l\u00e9gant, des chaussures sympas ou des essentiels chauds pour l&#8217;hiver &#8211; chez Hugo Boss, tout le monde en profite. Les femmes aussi peuvent profiter de l&#8217;offre avec des promotions int\u00e9ressantes sur les v\u00eatements et les accessoires.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chez Hugo Boss, le Black Friday offre jusqu&#8217;\u00e0 40% de r\u00e9duction sur des cat\u00e9gories qui changent tous les jours. Cela vaut donc la peine d&#8217;y jeter un coup d&#8217;\u0153il tous les jours ! Que ce soit un costume \u00e9l\u00e9gant, des chaussures sympas ou des essentiels chauds pour l&#8217;hiver &#8211; chez Hugo Boss, tout le monde [&hellip;]<\/p>\n","protected":false},"author":328,"featured_media":5134,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[6089],"tags":[],"dealstore":[359],"offerexpiration":[16317],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Jusqu&#039;\u00e0 40% chez Hugo Boss - blackfridaydeals.ch<\/title>\n<meta name=\"description\" content=\"Chez Hugo Boss, le Black Friday offre jusqu&#039;\u00e0 40% de r\u00e9duction sur des cat\u00e9gories qui changent tous les jours.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jusqu&#039;\u00e0 40% chez Hugo Boss - blackfridaydeals.ch\" \/>\n<meta property=\"og:description\" content=\"Chez Hugo Boss, le Black Friday offre jusqu&#039;\u00e0 40% de r\u00e9duction sur des cat\u00e9gories qui changent tous les jours.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.blackfridaydeals.ch\/fr\/rabais-chez-hugo-boss\/\" \/>\n<meta property=\"og:site_name\" content=\"blackfridaydeals.ch\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/blackfridaydealsch\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-23T15:21:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-14T09:59:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.blackfridaydeals.ch\/wp-content\/uploads\/2017\/10\/Hugo-Boss-Logo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"107\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Joy Wittwer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@blackfridaych\" \/>\n<meta name=\"twitter:site\" content=\"@blackfridaych\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joy Wittwer\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/rabais-chez-hugo-boss\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/rabais-chez-hugo-boss\/\"},\"author\":{\"name\":\"Joy Wittwer\",\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/#\/schema\/person\/a55393f59b60d60127468e78785d6b10\"},\"headline\":\"Jusqu&#8217;\u00e0 40% chez Hugo Boss\",\"datePublished\":\"2021-11-23T15:21:54+00:00\",\"dateModified\":\"2021-12-14T09:59:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/rabais-chez-hugo-boss\/\"},\"wordCount\":83,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/#organization\"},\"articleSection\":[\"Mode (non partner FR)\"],\"inLanguage\":\"fr-CH\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.blackfridaydeals.ch\/fr\/rabais-chez-hugo-boss\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/rabais-chez-hugo-boss\/\",\"url\":\"https:\/\/www.blackfridaydeals.ch\/fr\/rabais-chez-hugo-boss\/\",\"name\":\"Jusqu'\u00e0 40% chez Hugo Boss - blackfridaydeals.ch\",\"isPartOf\":{\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/#website\"},\"datePublished\":\"2021-11-23T15:21:54+00:00\",\"dateModified\":\"2021-12-14T09:59:31+00:00\",\"description\":\"Chez Hugo Boss, le Black Friday offre jusqu'\u00e0 40% de r\u00e9duction sur des cat\u00e9gories qui changent tous les jours.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/rabais-chez-hugo-boss\/#breadcrumb\"},\"inLanguage\":\"fr-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.blackfridaydeals.ch\/fr\/rabais-chez-hugo-boss\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/rabais-chez-hugo-boss\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.blackfridaydeals.ch\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jusqu&#8217;\u00e0 40% chez Hugo Boss\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/#website\",\"url\":\"https:\/\/www.blackfridaydeals.ch\/fr\/\",\"name\":\"blackfridaydeals.ch\",\"description\":\"Alle Angebote des Black Friday 2025 in der Schweiz\",\"publisher\":{\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/#organization\"},\"alternateName\":\"Black Friday Deals\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.blackfridaydeals.ch\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-CH\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/#organization\",\"name\":\"blackfridaydeals.ch\",\"alternateName\":\"Black Friday Deals\",\"url\":\"https:\/\/www.blackfridaydeals.ch\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CH\",\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.blackfridaydeals.ch\/wp-content\/uploads\/2023\/03\/app-icon-white-bg-jpg.jpg\",\"contentUrl\":\"https:\/\/www.blackfridaydeals.ch\/wp-content\/uploads\/2023\/03\/app-icon-white-bg-jpg.jpg\",\"width\":512,\"height\":512,\"caption\":\"blackfridaydeals.ch\"},\"image\":{\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/blackfridaydealsch\/\",\"https:\/\/twitter.com\/blackfridaych\",\"https:\/\/www.youtube.com\/channel\/UCNKXHacMw8AS34mBgzVx3FQ\",\"https:\/\/www.instagram.com\/blackfridaydeals.ch\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/#\/schema\/person\/a55393f59b60d60127468e78785d6b10\",\"name\":\"Joy Wittwer\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CH\",\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/009c9c32897a17f057bd673c922cb408?s=96&d=blank&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/009c9c32897a17f057bd673c922cb408?s=96&d=blank&r=g\",\"caption\":\"Joy Wittwer\"},\"description\":\"In den Bereichen Mode und Lifestyle, Beauty und Reisen kennt sich Joy aus. Sie findet dabei zuverl\u00e4ssig die besten Aktionen aus diesen Bereichen und teilt diese mit der Community.\",\"sameAs\":[\"https:\/\/www.linkedin.com\/in\/joywittwer\/\"],\"url\":\"https:\/\/www.blackfridaydeals.ch\/fr\/author\/joy\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jusqu'\u00e0 40% chez Hugo Boss - blackfridaydeals.ch","description":"Chez Hugo Boss, le Black Friday offre jusqu'\u00e0 40% de r\u00e9duction sur des cat\u00e9gories qui changent tous les jours.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Jusqu'\u00e0 40% chez Hugo Boss - blackfridaydeals.ch","og_description":"Chez Hugo Boss, le Black Friday offre jusqu'\u00e0 40% de r\u00e9duction sur des cat\u00e9gories qui changent tous les jours.","og_url":"https:\/\/www.blackfridaydeals.ch\/fr\/rabais-chez-hugo-boss\/","og_site_name":"blackfridaydeals.ch","article_publisher":"https:\/\/www.facebook.com\/blackfridaydealsch\/","article_published_time":"2021-11-23T15:21:54+00:00","article_modified_time":"2021-12-14T09:59:31+00:00","og_image":[{"width":300,"height":107,"url":"https:\/\/www.blackfridaydeals.ch\/wp-content\/uploads\/2017\/10\/Hugo-Boss-Logo.png","type":"image\/png"}],"author":"Joy Wittwer","twitter_card":"summary_large_image","twitter_creator":"@blackfridaych","twitter_site":"@blackfridaych","twitter_misc":{"Written by":"Joy Wittwer"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.blackfridaydeals.ch\/fr\/rabais-chez-hugo-boss\/#article","isPartOf":{"@id":"https:\/\/www.blackfridaydeals.ch\/fr\/rabais-chez-hugo-boss\/"},"author":{"name":"Joy Wittwer","@id":"https:\/\/www.blackfridaydeals.ch\/fr\/#\/schema\/person\/a55393f59b60d60127468e78785d6b10"},"headline":"Jusqu&#8217;\u00e0 40% chez Hugo Boss","datePublished":"2021-11-23T15:21:54+00:00","dateModified":"2021-12-14T09:59:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.blackfridaydeals.ch\/fr\/rabais-chez-hugo-boss\/"},"wordCount":83,"commentCount":0,"publisher":{"@id":"https:\/\/www.blackfridaydeals.ch\/fr\/#organization"},"articleSection":["Mode (non partner FR)"],"inLanguage":"fr-CH","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.blackfridaydeals.ch\/fr\/rabais-chez-hugo-boss\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.blackfridaydeals.ch\/fr\/rabais-chez-hugo-boss\/","url":"https:\/\/www.blackfridaydeals.ch\/fr\/rabais-chez-hugo-boss\/","name":"Jusqu'\u00e0 40% chez Hugo Boss - blackfridaydeals.ch","isPartOf":{"@id":"https:\/\/www.blackfridaydeals.ch\/fr\/#website"},"datePublished":"2021-11-23T15:21:54+00:00","dateModified":"2021-12-14T09:59:31+00:00","description":"Chez Hugo Boss, le Black Friday offre jusqu'\u00e0 40% de r\u00e9duction sur des cat\u00e9gories qui changent tous les jours.","breadcrumb":{"@id":"https:\/\/www.blackfridaydeals.ch\/fr\/rabais-chez-hugo-boss\/#breadcrumb"},"inLanguage":"fr-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.blackfridaydeals.ch\/fr\/rabais-chez-hugo-boss\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.blackfridaydeals.ch\/fr\/rabais-chez-hugo-boss\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.blackfridaydeals.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"Jusqu&#8217;\u00e0 40% chez Hugo Boss"}]},{"@type":"WebSite","@id":"https:\/\/www.blackfridaydeals.ch\/fr\/#website","url":"https:\/\/www.blackfridaydeals.ch\/fr\/","name":"blackfridaydeals.ch","description":"Alle Angebote des Black Friday 2025 in der Schweiz","publisher":{"@id":"https:\/\/www.blackfridaydeals.ch\/fr\/#organization"},"alternateName":"Black Friday Deals","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.blackfridaydeals.ch\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-CH"},{"@type":"Organization","@id":"https:\/\/www.blackfridaydeals.ch\/fr\/#organization","name":"blackfridaydeals.ch","alternateName":"Black Friday Deals","url":"https:\/\/www.blackfridaydeals.ch\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-CH","@id":"https:\/\/www.blackfridaydeals.ch\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.blackfridaydeals.ch\/wp-content\/uploads\/2023\/03\/app-icon-white-bg-jpg.jpg","contentUrl":"https:\/\/www.blackfridaydeals.ch\/wp-content\/uploads\/2023\/03\/app-icon-white-bg-jpg.jpg","width":512,"height":512,"caption":"blackfridaydeals.ch"},"image":{"@id":"https:\/\/www.blackfridaydeals.ch\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/blackfridaydealsch\/","https:\/\/twitter.com\/blackfridaych","https:\/\/www.youtube.com\/channel\/UCNKXHacMw8AS34mBgzVx3FQ","https:\/\/www.instagram.com\/blackfridaydeals.ch\/"]},{"@type":"Person","@id":"https:\/\/www.blackfridaydeals.ch\/fr\/#\/schema\/person\/a55393f59b60d60127468e78785d6b10","name":"Joy Wittwer","image":{"@type":"ImageObject","inLanguage":"fr-CH","@id":"https:\/\/www.blackfridaydeals.ch\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/009c9c32897a17f057bd673c922cb408?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/009c9c32897a17f057bd673c922cb408?s=96&d=blank&r=g","caption":"Joy Wittwer"},"description":"In den Bereichen Mode und Lifestyle, Beauty und Reisen kennt sich Joy aus. Sie findet dabei zuverl\u00e4ssig die besten Aktionen aus diesen Bereichen und teilt diese mit der Community.","sameAs":["https:\/\/www.linkedin.com\/in\/joywittwer\/"],"url":"https:\/\/www.blackfridaydeals.ch\/fr\/author\/joy\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.blackfridaydeals.ch\/fr\/wp-json\/wp\/v2\/posts\/45450"}],"collection":[{"href":"https:\/\/www.blackfridaydeals.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blackfridaydeals.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blackfridaydeals.ch\/fr\/wp-json\/wp\/v2\/users\/328"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blackfridaydeals.ch\/fr\/wp-json\/wp\/v2\/comments?post=45450"}],"version-history":[{"count":2,"href":"https:\/\/www.blackfridaydeals.ch\/fr\/wp-json\/wp\/v2\/posts\/45450\/revisions"}],"predecessor-version":[{"id":45476,"href":"https:\/\/www.blackfridaydeals.ch\/fr\/wp-json\/wp\/v2\/posts\/45450\/revisions\/45476"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.blackfridaydeals.ch\/fr\/wp-json\/wp\/v2\/media\/5134"}],"wp:attachment":[{"href":"https:\/\/www.blackfridaydeals.ch\/fr\/wp-json\/wp\/v2\/media?parent=45450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blackfridaydeals.ch\/fr\/wp-json\/wp\/v2\/categories?post=45450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blackfridaydeals.ch\/fr\/wp-json\/wp\/v2\/tags?post=45450"},{"taxonomy":"dealstore","embeddable":true,"href":"https:\/\/www.blackfridaydeals.ch\/fr\/wp-json\/wp\/v2\/dealstore?post=45450"},{"taxonomy":"offerexpiration","embeddable":true,"href":"https:\/\/www.blackfridaydeals.ch\/fr\/wp-json\/wp\/v2\/offerexpiration?post=45450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}