{"id":105610,"date":"2025-11-19T14:15:00","date_gmt":"2025-11-19T13:15:00","guid":{"rendered":"https:\/\/www.blackfridaydeals.ch\/chaussure-de-course-adidas-galaxy-6\/"},"modified":"2025-12-01T05:35:53","modified_gmt":"2025-12-01T04:35:53","slug":"chaussure-de-course-adidas-galaxy-6","status":"publish","type":"post","link":"https:\/\/www.blackfridaydeals.ch\/fr\/chaussure-de-course-adidas-galaxy-6\/","title":{"rendered":"Chaussure de course Adidas Galaxy 6"},"content":{"rendered":"<p>Il suffit de commencer \u00e0 courir. Avec cette chaussure de course adidas, vous serez particuli\u00e8rement \u00e0 l&#8217;aise, peu importe la longueur de votre journ\u00e9e. Alors que la tige l\u00e9g\u00e8re et a\u00e9r\u00e9e en mesh garde vos pieds agr\u00e9ablement frais, la semelle interm\u00e9diaire Cloudfoam assure un amorti optimal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il suffit de commencer \u00e0 courir. Avec cette chaussure de course adidas, vous serez particuli\u00e8rement \u00e0 l&#8217;aise, peu importe la longueur de votre journ\u00e9e. Alors que la tige l\u00e9g\u00e8re et a\u00e9r\u00e9e en mesh garde vos pieds agr\u00e9ablement frais, la semelle interm\u00e9diaire Cloudfoam assure un amorti optimal.<\/p>\n","protected":false},"author":348,"featured_media":105606,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[14212],"tags":[16532],"dealstore":[9220],"offerexpiration":[16317],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Chaussure de course Adidas Galaxy 6 - blackfridaydeals.ch<\/title>\n<meta name=\"description\" content=\"Il suffit de commencer \u00e0 courir. Avec cette chaussure de course adidas, vous serez particuli\u00e8rement \u00e0 l&#039;aise, peu importe la longueur de votre journ\u00e9e.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chaussure de course Adidas Galaxy 6 - blackfridaydeals.ch\" \/>\n<meta property=\"og:description\" content=\"Il suffit de commencer \u00e0 courir. Avec cette chaussure de course adidas, vous serez particuli\u00e8rement \u00e0 l&#039;aise, peu importe la longueur de votre journ\u00e9e.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.blackfridaydeals.ch\/fr\/chaussure-de-course-adidas-galaxy-6\/\" \/>\n<meta property=\"og:site_name\" content=\"blackfridaydeals.ch\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/blackfridaydealsch\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-19T13:15:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-01T04:35:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.blackfridaydeals.ch\/wp-content\/uploads\/2025\/11\/1f8760e5-8d92-4543-bdf7-ebbad464b7d9__laufschuh.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Luca Keller\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@blackfridaych\" \/>\n<meta name=\"twitter:site\" content=\"@blackfridaych\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Luca Keller\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/chaussure-de-course-adidas-galaxy-6\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/chaussure-de-course-adidas-galaxy-6\/\"},\"author\":{\"name\":\"Luca Keller\",\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/#\/schema\/person\/0aa4f873dece3b5c2303f1e386ff9e1b\"},\"headline\":\"Chaussure de course Adidas Galaxy 6\",\"datePublished\":\"2025-11-19T13:15:00+00:00\",\"dateModified\":\"2025-12-01T04:35:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/chaussure-de-course-adidas-galaxy-6\/\"},\"wordCount\":57,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/#organization\"},\"keywords\":[\"red-fashion-fr\"],\"articleSection\":[\"Top-Deals\"],\"inLanguage\":\"fr-CH\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.blackfridaydeals.ch\/fr\/chaussure-de-course-adidas-galaxy-6\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/chaussure-de-course-adidas-galaxy-6\/\",\"url\":\"https:\/\/www.blackfridaydeals.ch\/fr\/chaussure-de-course-adidas-galaxy-6\/\",\"name\":\"Chaussure de course Adidas Galaxy 6 - blackfridaydeals.ch\",\"isPartOf\":{\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/#website\"},\"datePublished\":\"2025-11-19T13:15:00+00:00\",\"dateModified\":\"2025-12-01T04:35:53+00:00\",\"description\":\"Il suffit de commencer \u00e0 courir. Avec cette chaussure de course adidas, vous serez particuli\u00e8rement \u00e0 l'aise, peu importe la longueur de votre journ\u00e9e.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/chaussure-de-course-adidas-galaxy-6\/#breadcrumb\"},\"inLanguage\":\"fr-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.blackfridaydeals.ch\/fr\/chaussure-de-course-adidas-galaxy-6\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/chaussure-de-course-adidas-galaxy-6\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.blackfridaydeals.ch\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adidas Galaxy 6\",\"item\":\"https:\/\/www.blackfridaydeals.ch\/fr\/adidas-galaxy-6\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Chaussure de course Adidas Galaxy 6\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/#website\",\"url\":\"https:\/\/www.blackfridaydeals.ch\/fr\/\",\"name\":\"blackfridaydeals.ch\",\"description\":\"Alle Angebote des Black Friday 2025 in der Schweiz\",\"publisher\":{\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/#organization\"},\"alternateName\":\"Black Friday Deals\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.blackfridaydeals.ch\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-CH\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/#organization\",\"name\":\"blackfridaydeals.ch\",\"alternateName\":\"Black Friday Deals\",\"url\":\"https:\/\/www.blackfridaydeals.ch\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CH\",\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.blackfridaydeals.ch\/wp-content\/uploads\/2023\/03\/app-icon-white-bg-jpg.jpg\",\"contentUrl\":\"https:\/\/www.blackfridaydeals.ch\/wp-content\/uploads\/2023\/03\/app-icon-white-bg-jpg.jpg\",\"width\":512,\"height\":512,\"caption\":\"blackfridaydeals.ch\"},\"image\":{\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/blackfridaydealsch\/\",\"https:\/\/twitter.com\/blackfridaych\",\"https:\/\/www.youtube.com\/channel\/UCNKXHacMw8AS34mBgzVx3FQ\",\"https:\/\/www.instagram.com\/blackfridaydeals.ch\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/#\/schema\/person\/0aa4f873dece3b5c2303f1e386ff9e1b\",\"name\":\"Luca Keller\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CH\",\"@id\":\"https:\/\/www.blackfridaydeals.ch\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f554621003806b1ce1b9a9a6ea54c40b?s=96&d=blank&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f554621003806b1ce1b9a9a6ea54c40b?s=96&d=blank&r=g\",\"caption\":\"Luca Keller\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/in\/frank-hartmann-a1b335297\/\"],\"url\":\"https:\/\/www.blackfridaydeals.ch\/fr\/author\/frank\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chaussure de course Adidas Galaxy 6 - blackfridaydeals.ch","description":"Il suffit de commencer \u00e0 courir. Avec cette chaussure de course adidas, vous serez particuli\u00e8rement \u00e0 l'aise, peu importe la longueur de votre journ\u00e9e.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Chaussure de course Adidas Galaxy 6 - blackfridaydeals.ch","og_description":"Il suffit de commencer \u00e0 courir. Avec cette chaussure de course adidas, vous serez particuli\u00e8rement \u00e0 l'aise, peu importe la longueur de votre journ\u00e9e.","og_url":"https:\/\/www.blackfridaydeals.ch\/fr\/chaussure-de-course-adidas-galaxy-6\/","og_site_name":"blackfridaydeals.ch","article_publisher":"https:\/\/www.facebook.com\/blackfridaydealsch\/","article_published_time":"2025-11-19T13:15:00+00:00","article_modified_time":"2025-12-01T04:35:53+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/www.blackfridaydeals.ch\/wp-content\/uploads\/2025\/11\/1f8760e5-8d92-4543-bdf7-ebbad464b7d9__laufschuh.png","type":"image\/png"}],"author":"Luca Keller","twitter_card":"summary_large_image","twitter_creator":"@blackfridaych","twitter_site":"@blackfridaych","twitter_misc":{"Written by":"Luca Keller"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.blackfridaydeals.ch\/fr\/chaussure-de-course-adidas-galaxy-6\/#article","isPartOf":{"@id":"https:\/\/www.blackfridaydeals.ch\/fr\/chaussure-de-course-adidas-galaxy-6\/"},"author":{"name":"Luca Keller","@id":"https:\/\/www.blackfridaydeals.ch\/fr\/#\/schema\/person\/0aa4f873dece3b5c2303f1e386ff9e1b"},"headline":"Chaussure de course Adidas Galaxy 6","datePublished":"2025-11-19T13:15:00+00:00","dateModified":"2025-12-01T04:35:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.blackfridaydeals.ch\/fr\/chaussure-de-course-adidas-galaxy-6\/"},"wordCount":57,"commentCount":0,"publisher":{"@id":"https:\/\/www.blackfridaydeals.ch\/fr\/#organization"},"keywords":["red-fashion-fr"],"articleSection":["Top-Deals"],"inLanguage":"fr-CH","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.blackfridaydeals.ch\/fr\/chaussure-de-course-adidas-galaxy-6\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.blackfridaydeals.ch\/fr\/chaussure-de-course-adidas-galaxy-6\/","url":"https:\/\/www.blackfridaydeals.ch\/fr\/chaussure-de-course-adidas-galaxy-6\/","name":"Chaussure de course Adidas Galaxy 6 - blackfridaydeals.ch","isPartOf":{"@id":"https:\/\/www.blackfridaydeals.ch\/fr\/#website"},"datePublished":"2025-11-19T13:15:00+00:00","dateModified":"2025-12-01T04:35:53+00:00","description":"Il suffit de commencer \u00e0 courir. Avec cette chaussure de course adidas, vous serez particuli\u00e8rement \u00e0 l'aise, peu importe la longueur de votre journ\u00e9e.","breadcrumb":{"@id":"https:\/\/www.blackfridaydeals.ch\/fr\/chaussure-de-course-adidas-galaxy-6\/#breadcrumb"},"inLanguage":"fr-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.blackfridaydeals.ch\/fr\/chaussure-de-course-adidas-galaxy-6\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.blackfridaydeals.ch\/fr\/chaussure-de-course-adidas-galaxy-6\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.blackfridaydeals.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"Adidas Galaxy 6","item":"https:\/\/www.blackfridaydeals.ch\/fr\/adidas-galaxy-6\/"},{"@type":"ListItem","position":3,"name":"Chaussure de course Adidas Galaxy 6"}]},{"@type":"WebSite","@id":"https:\/\/www.blackfridaydeals.ch\/fr\/#website","url":"https:\/\/www.blackfridaydeals.ch\/fr\/","name":"blackfridaydeals.ch","description":"Alle Angebote des Black Friday 2025 in der Schweiz","publisher":{"@id":"https:\/\/www.blackfridaydeals.ch\/fr\/#organization"},"alternateName":"Black Friday Deals","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.blackfridaydeals.ch\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-CH"},{"@type":"Organization","@id":"https:\/\/www.blackfridaydeals.ch\/fr\/#organization","name":"blackfridaydeals.ch","alternateName":"Black Friday Deals","url":"https:\/\/www.blackfridaydeals.ch\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-CH","@id":"https:\/\/www.blackfridaydeals.ch\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.blackfridaydeals.ch\/wp-content\/uploads\/2023\/03\/app-icon-white-bg-jpg.jpg","contentUrl":"https:\/\/www.blackfridaydeals.ch\/wp-content\/uploads\/2023\/03\/app-icon-white-bg-jpg.jpg","width":512,"height":512,"caption":"blackfridaydeals.ch"},"image":{"@id":"https:\/\/www.blackfridaydeals.ch\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/blackfridaydealsch\/","https:\/\/twitter.com\/blackfridaych","https:\/\/www.youtube.com\/channel\/UCNKXHacMw8AS34mBgzVx3FQ","https:\/\/www.instagram.com\/blackfridaydeals.ch\/"]},{"@type":"Person","@id":"https:\/\/www.blackfridaydeals.ch\/fr\/#\/schema\/person\/0aa4f873dece3b5c2303f1e386ff9e1b","name":"Luca Keller","image":{"@type":"ImageObject","inLanguage":"fr-CH","@id":"https:\/\/www.blackfridaydeals.ch\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f554621003806b1ce1b9a9a6ea54c40b?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f554621003806b1ce1b9a9a6ea54c40b?s=96&d=blank&r=g","caption":"Luca Keller"},"sameAs":["https:\/\/www.linkedin.com\/in\/frank-hartmann-a1b335297\/"],"url":"https:\/\/www.blackfridaydeals.ch\/fr\/author\/frank\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.blackfridaydeals.ch\/fr\/wp-json\/wp\/v2\/posts\/105610"}],"collection":[{"href":"https:\/\/www.blackfridaydeals.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blackfridaydeals.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blackfridaydeals.ch\/fr\/wp-json\/wp\/v2\/users\/348"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blackfridaydeals.ch\/fr\/wp-json\/wp\/v2\/comments?post=105610"}],"version-history":[{"count":1,"href":"https:\/\/www.blackfridaydeals.ch\/fr\/wp-json\/wp\/v2\/posts\/105610\/revisions"}],"predecessor-version":[{"id":105783,"href":"https:\/\/www.blackfridaydeals.ch\/fr\/wp-json\/wp\/v2\/posts\/105610\/revisions\/105783"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.blackfridaydeals.ch\/fr\/wp-json\/wp\/v2\/media\/105606"}],"wp:attachment":[{"href":"https:\/\/www.blackfridaydeals.ch\/fr\/wp-json\/wp\/v2\/media?parent=105610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blackfridaydeals.ch\/fr\/wp-json\/wp\/v2\/categories?post=105610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blackfridaydeals.ch\/fr\/wp-json\/wp\/v2\/tags?post=105610"},{"taxonomy":"dealstore","embeddable":true,"href":"https:\/\/www.blackfridaydeals.ch\/fr\/wp-json\/wp\/v2\/dealstore?post=105610"},{"taxonomy":"offerexpiration","embeddable":true,"href":"https:\/\/www.blackfridaydeals.ch\/fr\/wp-json\/wp\/v2\/offerexpiration?post=105610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}